{"id":1342,"count":1,"description":"","link":"https:\/\/medialit.in\/thevoices\/tag\/law\/","name":"law","slug":"law","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"Zl4g1yZVyRBdQ8viEtuz8xpS2jQQdiFmglKLAUttdtA\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/medialit.in\/thevoices\/tag\/law\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1342\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/medialit.in\\\/thevoices\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/law\\\/#listItem\",\"name\":\"law\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/law\\\/#listItem\",\"position\":2,\"name\":\"law\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1342\\\/#collectionpage\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1342\\\/\",\"name\":\"law - The Voices\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1342\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#organization\",\"name\":\"The Voices\",\"description\":\"Let's Break the Silence\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#website\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/\",\"name\":\"The Voices\",\"description\":\"Let's Break the Silence\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"law - The Voices","description":"","canonical_url":"https:\/\/medialit.in\/thevoices\/tag\/law\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"Zl4g1yZVyRBdQ8viEtuz8xpS2jQQdiFmglKLAUttdtA","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/tags\/1342\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/medialit.in\/thevoices#listItem","position":1,"name":"Home","item":"https:\/\/medialit.in\/thevoices","nextItem":{"@type":"ListItem","@id":"https:\/\/medialit.in\/thevoices\/tag\/law\/#listItem","name":"law"}},{"@type":"ListItem","@id":"https:\/\/medialit.in\/thevoices\/tag\/law\/#listItem","position":2,"name":"law","previousItem":{"@type":"ListItem","@id":"https:\/\/medialit.in\/thevoices#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/tags\/1342\/#collectionpage","url":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/tags\/1342\/","name":"law - The Voices","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/medialit.in\/thevoices\/#website"},"breadcrumb":{"@id":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/tags\/1342\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/medialit.in\/thevoices\/#organization","name":"The Voices","description":"Let's Break the Silence","url":"https:\/\/medialit.in\/thevoices\/"},{"@type":"WebSite","@id":"https:\/\/medialit.in\/thevoices\/#website","url":"https:\/\/medialit.in\/thevoices\/","name":"The Voices","description":"Let's Break the Silence","inLanguage":"en-US","publisher":{"@id":"https:\/\/medialit.in\/thevoices\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/medialit.in\/thevoices\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tlaw\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/medialit.in\/thevoices"},{"label":"law","link":"https:\/\/medialit.in\/thevoices\/tag\/law\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>law Archives - The Voices<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medialit.in\/thevoices\/tag\/law\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"law Archives - The Voices\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medialit.in\/thevoices\/tag\/law\/\" \/>\n<meta property=\"og:site_name\" content=\"The Voices\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheVoices_IGNOU\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/law\\\/\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/law\\\/\",\"name\":\"law Archives - The Voices\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/law\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/law\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"law\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#website\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/\",\"name\":\"The Voices\",\"description\":\"Let&#039;s Break the Silence\",\"publisher\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#organization\",\"name\":\"The Voices\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-cropped-cropped-Voice-Logo-without-name.png\",\"contentUrl\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-cropped-cropped-Voice-Logo-without-name.png\",\"width\":512,\"height\":512,\"caption\":\"The Voices\"},\"image\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thevoices.ignou\",\"https:\\\/\\\/x.com\\\/TheVoices_IGNOU\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCsLvQ1nfCY0qrxFt8TAnf7g\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"law Archives - The Voices","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medialit.in\/thevoices\/tag\/law\/","og_locale":"en_US","og_type":"article","og_title":"law Archives - The Voices","og_url":"https:\/\/medialit.in\/thevoices\/tag\/law\/","og_site_name":"The Voices","twitter_card":"summary_large_image","twitter_site":"@TheVoices_IGNOU","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/medialit.in\/thevoices\/tag\/law\/","url":"https:\/\/medialit.in\/thevoices\/tag\/law\/","name":"law Archives - The Voices","isPartOf":{"@id":"https:\/\/medialit.in\/thevoices\/#website"},"breadcrumb":{"@id":"https:\/\/medialit.in\/thevoices\/tag\/law\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/medialit.in\/thevoices\/tag\/law\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/medialit.in\/thevoices\/"},{"@type":"ListItem","position":2,"name":"law"}]},{"@type":"WebSite","@id":"https:\/\/medialit.in\/thevoices\/#website","url":"https:\/\/medialit.in\/thevoices\/","name":"The Voices","description":"Let&#039;s Break the Silence","publisher":{"@id":"https:\/\/medialit.in\/thevoices\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medialit.in\/thevoices\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/medialit.in\/thevoices\/#organization","name":"The Voices","url":"https:\/\/medialit.in\/thevoices\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/medialit.in\/thevoices\/#\/schema\/logo\/image\/","url":"https:\/\/medialit.in\/thevoices\/wp-content\/uploads\/2021\/02\/cropped-cropped-cropped-Voice-Logo-without-name.png","contentUrl":"https:\/\/medialit.in\/thevoices\/wp-content\/uploads\/2021\/02\/cropped-cropped-cropped-Voice-Logo-without-name.png","width":512,"height":512,"caption":"The Voices"},"image":{"@id":"https:\/\/medialit.in\/thevoices\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thevoices.ignou","https:\/\/x.com\/TheVoices_IGNOU","https:\/\/www.youtube.com\/channel\/UCsLvQ1nfCY0qrxFt8TAnf7g\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/tags\/1342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/posts?tags=1342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}