{"id":4495,"count":1,"description":"","link":"https:\/\/medialit.in\/thevoices\/tag\/melbourne-olympic\/","name":"Melbourne Olympic","slug":"melbourne-olympic","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Melbourne Olympic Archives - The Voices<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medialit.in\/thevoices\/tag\/melbourne-olympic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Melbourne Olympic Archives - The Voices\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medialit.in\/thevoices\/tag\/melbourne-olympic\/\" \/>\n<meta property=\"og:site_name\" content=\"The Voices\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TheVoices_IGNOU\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/melbourne-olympic\\\/\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/melbourne-olympic\\\/\",\"name\":\"Melbourne Olympic Archives - The Voices\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/melbourne-olympic\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/tag\\\/melbourne-olympic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Melbourne Olympic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#website\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/\",\"name\":\"The Voices\",\"description\":\"Let&#039;s Break the Silence\",\"publisher\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#organization\",\"name\":\"The Voices\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-cropped-cropped-Voice-Logo-without-name.png\",\"contentUrl\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-cropped-cropped-Voice-Logo-without-name.png\",\"width\":512,\"height\":512,\"caption\":\"The Voices\"},\"image\":{\"@id\":\"https:\\\/\\\/medialit.in\\\/thevoices\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/thevoices.ignou\",\"https:\\\/\\\/x.com\\\/TheVoices_IGNOU\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCsLvQ1nfCY0qrxFt8TAnf7g\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Melbourne Olympic Archives - The Voices","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medialit.in\/thevoices\/tag\/melbourne-olympic\/","og_locale":"en_US","og_type":"article","og_title":"Melbourne Olympic Archives - The Voices","og_url":"https:\/\/medialit.in\/thevoices\/tag\/melbourne-olympic\/","og_site_name":"The Voices","twitter_card":"summary_large_image","twitter_site":"@TheVoices_IGNOU","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/medialit.in\/thevoices\/tag\/melbourne-olympic\/","url":"https:\/\/medialit.in\/thevoices\/tag\/melbourne-olympic\/","name":"Melbourne Olympic Archives - The Voices","isPartOf":{"@id":"https:\/\/medialit.in\/thevoices\/#website"},"breadcrumb":{"@id":"https:\/\/medialit.in\/thevoices\/tag\/melbourne-olympic\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/medialit.in\/thevoices\/tag\/melbourne-olympic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/medialit.in\/thevoices\/"},{"@type":"ListItem","position":2,"name":"Melbourne Olympic"}]},{"@type":"WebSite","@id":"https:\/\/medialit.in\/thevoices\/#website","url":"https:\/\/medialit.in\/thevoices\/","name":"The Voices","description":"Let&#039;s Break the Silence","publisher":{"@id":"https:\/\/medialit.in\/thevoices\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medialit.in\/thevoices\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/medialit.in\/thevoices\/#organization","name":"The Voices","url":"https:\/\/medialit.in\/thevoices\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/medialit.in\/thevoices\/#\/schema\/logo\/image\/","url":"https:\/\/medialit.in\/thevoices\/wp-content\/uploads\/2021\/02\/cropped-cropped-cropped-Voice-Logo-without-name.png","contentUrl":"https:\/\/medialit.in\/thevoices\/wp-content\/uploads\/2021\/02\/cropped-cropped-cropped-Voice-Logo-without-name.png","width":512,"height":512,"caption":"The Voices"},"image":{"@id":"https:\/\/medialit.in\/thevoices\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/thevoices.ignou","https:\/\/x.com\/TheVoices_IGNOU","https:\/\/www.youtube.com\/channel\/UCsLvQ1nfCY0qrxFt8TAnf7g\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/tags\/4495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medialit.in\/thevoices\/wp-json\/wp\/v2\/posts?tags=4495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}